{"id":1334,"date":"2016-01-19T11:46:54","date_gmt":"2016-01-19T11:46:54","guid":{"rendered":"http:\/\/anpsthemes.com\/construction\/?page_id=1334"},"modified":"2016-01-19T11:46:54","modified_gmt":"2016-01-19T11:46:54","slug":"tables","status":"publish","type":"page","link":"https:\/\/preview.limorent.anpsthemes.com\/demo1\/tables\/","title":{"rendered":"Tables"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1453203752319{margin-bottom: 20px !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;TABLES&#8221; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;title&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1453204355007{margin-bottom: 0px !important;}&#8221;][vc_column]<div class='table-responsive'><table class='table table-bordered'><thead ><tr><th>TITLE 1<\/th><th>TITLE 2<\/th><th>TITLE 3<\/th><th>TITLE 4<\/th><th>TITLE 5<\/th><th>TITLE 6<\/th><th>TITLE 7<\/th><\/tr><\/thead><tbody><tr><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><\/tr><tr><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><\/tr><tr><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><\/tr><tr><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><\/tr><\/tbody><\/table><\/div>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1453204367356{margin-bottom: 0px !important;}&#8221;][vc_column]<div class='table-responsive'><table class='table'><thead  class='bg-primary'><tr><th>TITLE 1<\/th><th>TITLE 2<\/th><th>TITLE 3<\/th><th>TITLE 4<\/th><th>TITLE 5<\/th><th>TITLE 6<\/th><th>TITLE 7<\/th><\/tr><\/thead><tbody><tr><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><\/tr><tr><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><\/tr><tr><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><\/tr><tr><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><\/tr><\/tbody><\/table><\/div>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1453204373223{margin-bottom: 0px !important;}&#8221;][vc_column]<div class='table-responsive'><table class='table table-striped'><thead  class='bg-primary'><tr><th>TITLE 1<\/th><th>TITLE 2<\/th><th>TITLE 3<\/th><th>TITLE 4<\/th><th>TITLE 5<\/th><th>TITLE 6<\/th><th>TITLE 7<\/th><\/tr><\/thead><tbody><tr><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><\/tr><tr><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><\/tr><tr><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><\/tr><tr><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><td>Lorem ipsum<\/td><\/tr><\/tbody><\/table><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1453203752319{margin-bottom: 20px !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;TABLES&#8221; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;title&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1453204355007{margin-bottom: 0px !important;}&#8221;][vc_column][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1453204367356{margin-bottom: 0px !important;}&#8221;][vc_column][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1453204373223{margin-bottom: 0px !important;}&#8221;][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1334","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/preview.limorent.anpsthemes.com\/demo1\/wp-json\/wp\/v2\/pages\/1334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preview.limorent.anpsthemes.com\/demo1\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/preview.limorent.anpsthemes.com\/demo1\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/preview.limorent.anpsthemes.com\/demo1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/preview.limorent.anpsthemes.com\/demo1\/wp-json\/wp\/v2\/comments?post=1334"}],"version-history":[{"count":0,"href":"https:\/\/preview.limorent.anpsthemes.com\/demo1\/wp-json\/wp\/v2\/pages\/1334\/revisions"}],"wp:attachment":[{"href":"https:\/\/preview.limorent.anpsthemes.com\/demo1\/wp-json\/wp\/v2\/media?parent=1334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}