{"id":1347,"date":"2016-01-19T12:06:27","date_gmt":"2016-01-19T12:06:27","guid":{"rendered":"http:\/\/anpsthemes.com\/construction\/?page_id=1347"},"modified":"2016-01-19T12:06:27","modified_gmt":"2016-01-19T12:06:27","slug":"notifications","status":"publish","type":"page","link":"https:\/\/preview.limorent.anpsthemes.com\/demo2\/notifications\/","title":{"rendered":"Notifications"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1453205070715{margin-bottom: 20px !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;NOTIFICATIONS&#8221; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;title&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1453205367667{margin-bottom: 40px !important;}&#8221;][vc_column]<div class=\"alert alert-info\"><button type=\"button\" class=\"close\" data-dismiss=\"alert\" aria-hidden=\"true\"><i class=\"fa fa-remove\"><\/i><\/button><i class=\"fa fa-bell-o\"><\/i> Information Message! Your Message Goes Here<\/div><div class=\"alert alert-danger\"><button type=\"button\" class=\"close\" data-dismiss=\"alert\" aria-hidden=\"true\"><i class=\"fa fa-remove\"><\/i><\/button><i class=\"fa fa-exclamation\"><\/i> Danger Message! Your Message Goes Here<\/div><div class=\"alert alert-warning\"><button type=\"button\" class=\"close\" data-dismiss=\"alert\" aria-hidden=\"true\"><i class=\"fa fa-remove\"><\/i><\/button><i class=\"fa fa-info\"><\/i> Warning Message! Your Message Goes Here<\/div><div class=\"alert alert-success\"><button type=\"button\" class=\"close\" data-dismiss=\"alert\" aria-hidden=\"true\"><i class=\"fa fa-remove\"><\/i><\/button><i class=\"fa fa-check\"><\/i> Success Message! Your Message Goes Here<\/div><div class=\"alert alert-useful\"><button type=\"button\" class=\"close\" data-dismiss=\"alert\" aria-hidden=\"true\"><i class=\"fa fa-remove\"><\/i><\/button><i class=\"fa fa-lightbulb-o\"><\/i> Useful Message! Your Message Goes Here<\/div><div class=\"alert alert-normal\"><button type=\"button\" class=\"close\" data-dismiss=\"alert\" aria-hidden=\"true\"><i class=\"fa fa-remove\"><\/i><\/button><i class=\"fa fa-hand-o-right\"><\/i> Normal Message! Your Message Goes Here<\/div>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1453205381089{margin-bottom: 40px !important;}&#8221;][vc_column]<div class=\"alert alert-info-style-2\"><button type=\"button\" class=\"close\" data-dismiss=\"alert\" aria-hidden=\"true\"><i class=\"fa fa-remove\"><\/i><\/button><i class=\"fa fa-bell-o\"><\/i> Information Message! Your Message Goes Here<\/div><div class=\"alert alert-danger-style-2\"><button type=\"button\" class=\"close\" data-dismiss=\"alert\" aria-hidden=\"true\"><i class=\"fa fa-remove\"><\/i><\/button><i class=\"fa fa-exclamation\"><\/i> Danger Message! Your Message Goes Here<\/div><div class=\"alert alert-warning-style-2\"><button type=\"button\" class=\"close\" data-dismiss=\"alert\" aria-hidden=\"true\"><i class=\"fa fa-remove\"><\/i><\/button><i class=\"fa fa-info\"><\/i> Warning Message! Your Message Goes Here<\/div><div class=\"alert alert-success-style-2\"><button type=\"button\" class=\"close\" data-dismiss=\"alert\" aria-hidden=\"true\"><i class=\"fa fa-remove\"><\/i><\/button><i class=\"fa fa-check\"><\/i> Success Message! Your Message Goes Here<\/div><div class=\"alert alert-useful-style-2\"><button type=\"button\" class=\"close\" data-dismiss=\"alert\" aria-hidden=\"true\"><i class=\"fa fa-remove\"><\/i><\/button><i class=\"fa fa-lightbulb-o\"><\/i> Useful Message! Your Message Goes Here<\/div><div class=\"alert alert-normal-style-2\"><button type=\"button\" class=\"close\" data-dismiss=\"alert\" aria-hidden=\"true\"><i class=\"fa fa-remove\"><\/i><\/button><i class=\"fa fa-hand-o-right\"><\/i> Normal Message! Your Message Goes Here<\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1453205070715{margin-bottom: 20px !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;NOTIFICATIONS&#8221; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;title&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1453205367667{margin-bottom: 40px !important;}&#8221;][vc_column][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1453205381089{margin-bottom: 40px !important;}&#8221;][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1347","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-json\/wp\/v2\/pages\/1347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-json\/wp\/v2\/comments?post=1347"}],"version-history":[{"count":0,"href":"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-json\/wp\/v2\/pages\/1347\/revisions"}],"wp:attachment":[{"href":"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-json\/wp\/v2\/media?parent=1347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}