{"id":2264,"date":"2017-01-09T20:21:27","date_gmt":"2017-01-09T20:21:27","guid":{"rendered":"http:\/\/anpsthemes.com\/limorent\/demo-1\/?page_id=2264"},"modified":"2017-01-09T20:21:27","modified_gmt":"2017-01-09T20:21:27","slug":"service-rates","status":"publish","type":"page","link":"https:\/\/preview.limorent.anpsthemes.com\/demo2\/service-rates\/","title":{"rendered":"Service rates"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<div class=\"rate-table-wrap\"><table class='rate-table rate-table--col-3'><thead><tr><th class=\"rate-table__empty\"><\/th><th class=\"rate-table__empty\"><\/th><th class='rate-table__heading rate-table__heading--featured rate-table--active'><div class='rate-table__heading-text'>HOURLY RATE<\/div><\/th><th class='rate-table__heading'><div class='rate-table__heading-text'>DAILY RATE<\/div><\/th><th class='rate-table__heading'><div class='rate-table__heading-text'>ONE TIME RATE<\/div><\/th><\/tr><\/thead><tbody><tr><th class='rate-table__heading-body' colspan='2'><div class='rate-table__heading-body-wrap'><a class='rate-table__name' href='https:\/\/preview.limorent.anpsthemes.com\/demo2\/fleet\/lincoln-classic-sedan\/'>LINCOLN CLASSIC SEDAN<\/a><a class='rate-table__image' href='https:\/\/preview.limorent.anpsthemes.com\/demo2\/fleet\/lincoln-classic-sedan\/'><img loading=\"lazy\" decoding=\"async\" width=\"369\" height=\"150\" src=\"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car3.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car3.jpg 369w, https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car3-300x122.jpg 300w\" sizes=\"auto, (max-width: 369px) 100vw, 369px\" \/><\/a><\/div><\/th><td class='rate-table__data rate-table__data--featured rate-table--active'><span class='rate-table__data-price'>$49<\/span><span class='rate-table__data-type'> \/ hour<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><td class='rate-table__data'><span class='rate-table__data-price'>$199<\/span><span class='rate-table__data-type'> \/ day<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><td class='rate-table__data'><span class='rate-table__data-price'>$110<\/span><span class='rate-table__data-type'> \/ one time<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><\/tr><tr><th class='rate-table__heading-body' colspan='2'><div class='rate-table__heading-body-wrap'><a class='rate-table__name' href='https:\/\/preview.limorent.anpsthemes.com\/demo2\/fleet\/lincoln-beg-stretch-sedan\/'>LINCOLN BEG STRETCH SEDAN<\/a><a class='rate-table__image' href='https:\/\/preview.limorent.anpsthemes.com\/demo2\/fleet\/lincoln-beg-stretch-sedan\/'><img loading=\"lazy\" decoding=\"async\" width=\"369\" height=\"150\" src=\"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car6.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car6.jpg 369w, https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car6-300x122.jpg 300w\" sizes=\"auto, (max-width: 369px) 100vw, 369px\" \/><\/a><\/div><\/th><td class='rate-table__data rate-table__data--featured rate-table--active'><span class='rate-table__data-price'>$88<\/span><span class='rate-table__data-type'> \/ hour<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><td class='rate-table__data'><span class='rate-table__data-price'>$499<\/span><span class='rate-table__data-type'> \/ day<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><td class='rate-table__data'><span class='rate-table__data-price'>$129<\/span><span class='rate-table__data-type'> \/ one time<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><\/tr><tr><th class='rate-table__heading-body' colspan='2'><div class='rate-table__heading-body-wrap'><a class='rate-table__name' href='https:\/\/preview.limorent.anpsthemes.com\/demo2\/fleet\/lincoln-sedan-back\/'>LINCOLN SEDAN BACK<\/a><a class='rate-table__image' href='https:\/\/preview.limorent.anpsthemes.com\/demo2\/fleet\/lincoln-sedan-back\/'><img loading=\"lazy\" decoding=\"async\" width=\"369\" height=\"150\" src=\"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car9.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car9.jpg 369w, https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car9-300x122.jpg 300w\" sizes=\"auto, (max-width: 369px) 100vw, 369px\" \/><\/a><\/div><\/th><td class='rate-table__data rate-table__data--featured rate-table--active'><span class='rate-table__data-price'>$70<\/span><span class='rate-table__data-type'> \/ hour<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><td class='rate-table__data'><span class='rate-table__data-price'>$299<\/span><span class='rate-table__data-type'> \/ day<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><td class='rate-table__data'><span class='rate-table__data-price'>$110<\/span><span class='rate-table__data-type'> \/ one time<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><\/tr><tr><th class='rate-table__heading-body' colspan='2'><div class='rate-table__heading-body-wrap'><a class='rate-table__name' href='https:\/\/preview.limorent.anpsthemes.com\/demo2\/fleet\/rolls-royce-big-sedan\/'>ROLLS ROYCE BIG SEDAN<\/a><a class='rate-table__image' href='https:\/\/preview.limorent.anpsthemes.com\/demo2\/fleet\/rolls-royce-big-sedan\/'><img loading=\"lazy\" decoding=\"async\" width=\"369\" height=\"150\" src=\"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car4.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car4.jpg 369w, https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car4-300x122.jpg 300w\" sizes=\"auto, (max-width: 369px) 100vw, 369px\" \/><\/a><\/div><\/th><td class='rate-table__data rate-table__data--featured rate-table--active'><span class='rate-table__data-price'>$79<\/span><span class='rate-table__data-type'> \/ hour<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><td class='rate-table__data'><span class='rate-table__data-price'>$399<\/span><span class='rate-table__data-type'> \/ day<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><td class='rate-table__data'><span class='rate-table__data-price'>$110<\/span><span class='rate-table__data-type'> \/ one time<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><\/tr><tr><th class='rate-table__heading-body' colspan='2'><div class='rate-table__heading-body-wrap'><a class='rate-table__name' href='https:\/\/preview.limorent.anpsthemes.com\/demo2\/fleet\/jaguar-sedan\/'>JAGUAR SEDAN<\/a><a class='rate-table__image' href='https:\/\/preview.limorent.anpsthemes.com\/demo2\/fleet\/jaguar-sedan\/'><img loading=\"lazy\" decoding=\"async\" width=\"369\" height=\"150\" src=\"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car8.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car8.jpg 369w, https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car8-300x122.jpg 300w\" sizes=\"auto, (max-width: 369px) 100vw, 369px\" \/><\/a><\/div><\/th><td class='rate-table__data rate-table__data--featured rate-table--active'><span class='rate-table__data-price'>$89<\/span><span class='rate-table__data-type'> \/ hour<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><td class='rate-table__data'><span class='rate-table__data-price'>$399<\/span><span class='rate-table__data-type'> \/ day<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><td class='rate-table__data'><span class='rate-table__data-price'>$110<\/span><span class='rate-table__data-type'> \/ one time<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><\/tr><tr><th class='rate-table__heading-body' colspan='2'><div class='rate-table__heading-body-wrap'><a class='rate-table__name' href='https:\/\/preview.limorent.anpsthemes.com\/demo2\/fleet\/lincoln-long-limo\/'>LINCOLN LONG LIMO<\/a><a class='rate-table__image' href='https:\/\/preview.limorent.anpsthemes.com\/demo2\/fleet\/lincoln-long-limo\/'><img loading=\"lazy\" decoding=\"async\" width=\"369\" height=\"150\" src=\"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car7.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car7.jpg 369w, https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car7-300x122.jpg 300w\" sizes=\"auto, (max-width: 369px) 100vw, 369px\" \/><\/a><\/div><\/th><td class='rate-table__data rate-table__data--featured rate-table--active'><span class='rate-table__data-price'>$79<\/span><span class='rate-table__data-type'> \/ hour<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><td class='rate-table__data'><span class='rate-table__data-price'>$399<\/span><span class='rate-table__data-type'> \/ day<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><td class='rate-table__data'><span class='rate-table__data-price'>$110<\/span><span class='rate-table__data-type'> \/ one time<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><\/tr><tr><th class='rate-table__heading-body' colspan='2'><div class='rate-table__heading-body-wrap'><a class='rate-table__name' href='https:\/\/preview.limorent.anpsthemes.com\/demo2\/fleet\/mercedes-long-limo\/'>MERCEDES LONG LIMO<\/a><a class='rate-table__image' href='https:\/\/preview.limorent.anpsthemes.com\/demo2\/fleet\/mercedes-long-limo\/'><img loading=\"lazy\" decoding=\"async\" width=\"369\" height=\"150\" src=\"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car2.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car2.jpg 369w, https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car2-300x122.jpg 300w\" sizes=\"auto, (max-width: 369px) 100vw, 369px\" \/><\/a><\/div><\/th><td class='rate-table__data rate-table__data--featured rate-table--active'><span class='rate-table__data-price'>$99<\/span><span class='rate-table__data-type'> \/ hour<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><td class='rate-table__data'><span class='rate-table__data-price'>$499<\/span><span class='rate-table__data-type'> \/ day<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><td class='rate-table__data'><span class='rate-table__data-price'>$165<\/span><span class='rate-table__data-type'> \/ one time<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><\/tr><tr><th class='rate-table__heading-body' colspan='2'><div class='rate-table__heading-body-wrap'><a class='rate-table__name' href='https:\/\/preview.limorent.anpsthemes.com\/demo2\/fleet\/mercedes-sedan\/'>MERCEDES SEDAN<\/a><a class='rate-table__image' href='https:\/\/preview.limorent.anpsthemes.com\/demo2\/fleet\/mercedes-sedan\/'><img loading=\"lazy\" decoding=\"async\" width=\"369\" height=\"150\" src=\"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car5.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car5.jpg 369w, https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car5-300x122.jpg 300w\" sizes=\"auto, (max-width: 369px) 100vw, 369px\" \/><\/a><\/div><\/th><td class='rate-table__data rate-table__data--featured rate-table--active'><span class='rate-table__data-price'>$69<\/span><span class='rate-table__data-type'> \/ hour<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><td class='rate-table__data'><span class='rate-table__data-price'>$369<\/span><span class='rate-table__data-type'> \/ day<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><td class='rate-table__data'><span class='rate-table__data-price'>$100<\/span><span class='rate-table__data-type'> \/ one time<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><\/tr><tr><th class='rate-table__heading-body' colspan='2'><div class='rate-table__heading-body-wrap'><a class='rate-table__name' href='https:\/\/preview.limorent.anpsthemes.com\/demo2\/fleet\/cadillac-escaled-limo\/'>CADILLAC ESCALED LIMO<\/a><a class='rate-table__image' href='https:\/\/preview.limorent.anpsthemes.com\/demo2\/fleet\/cadillac-escaled-limo\/'><img loading=\"lazy\" decoding=\"async\" width=\"369\" height=\"150\" src=\"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car1v2.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car1v2.jpg 369w, https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-content\/uploads\/sites\/3\/2017\/01\/car1v2-300x122.jpg 300w\" sizes=\"auto, (max-width: 369px) 100vw, 369px\" \/><\/a><\/div><\/th><td class='rate-table__data rate-table__data--featured rate-table--active'><span class='rate-table__data-price'>$79<\/span><span class='rate-table__data-type'> \/ hour<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><td class='rate-table__data'><span class='rate-table__data-price'>$399<\/span><span class='rate-table__data-type'> \/ day<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><td class='rate-table__data'><span class='rate-table__data-price'>$110<\/span><span class='rate-table__data-type'> \/ one time<\/span><div class='rate-table__data-text'>*additional fuel charges<\/div><\/td><\/tr><\/tbody><tfoot><tr><td><\/td><td><\/td><td class='rate-table__data-footer rate-table__data-footer--featured rate-table--active'><button class='rate-table__button'>Book now<\/button><\/td><td class='rate-table__data-footer'><button class='rate-table__button'>Book now<\/button><\/td><td class='rate-table__data-footer'><button class='rate-table__button'>Book now<\/button><\/td><\/tr><\/tfoot><\/table><div class=\"fleet__lightbox\">\n                <button class=\"fleet__lightbox-close fa fa-close\"><\/button>\n                <div class=\"fleet__lightbox-content\">\n                    <div class=\"container\">\n                        <div class=\"row\">\n                            <div class=\"col-sm-4\"><\/div>\n                            <div class=\"col-sm-8\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1831-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1831\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/demo2\/wp-json\/wp\/v2\/pages\/2264#wpcf7-f1831-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1831\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1831-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<fieldset class=\"form-group col-md-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"name\" \/><\/span>\n\t\t<\/p>\n\t<\/fieldset>\n\t<fieldset class=\"form-group col-md-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"last-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Last Name\" value=\"\" type=\"text\" name=\"last-name\" \/><\/span>\n\t\t<\/p>\n\t<\/fieldset>\n<\/div>\n<div class=\"row\">\n\t<fieldset class=\"form-group col-md-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t<\/p>\n\t<\/fieldset>\n\t<fieldset class=\"form-group col-md-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone\" value=\"\" type=\"tel\" name=\"phone\" \/><\/span>\n\t\t<\/p>\n\t<\/fieldset>\n<\/div>\n<div class=\"row\">\n\t<fieldset class=\"form-group col-md-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"type\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"type\"><option value=\"$49 \/ hour\">$49 \/ hour<\/option><option value=\"$199 \/ day\">$199 \/ day<\/option><option value=\"$110 \/ one time\">$110 \/ one time<\/option><option value=\"$88 \/ hour\">$88 \/ hour<\/option><option value=\"$499 \/ day\">$499 \/ day<\/option><option value=\"$129 \/ one time\">$129 \/ one time<\/option><option value=\"$70 \/ hour\">$70 \/ hour<\/option><option value=\"$299 \/ day\">$299 \/ day<\/option><option value=\"$110 \/ one time\">$110 \/ one time<\/option><option value=\"$79 \/ hour\">$79 \/ hour<\/option><option value=\"$399 \/ day\">$399 \/ day<\/option><option value=\"$110 \/ one time\">$110 \/ one time<\/option><option value=\"$89 \/ hour\">$89 \/ hour<\/option><option value=\"$399 \/ day\">$399 \/ day<\/option><option value=\"$110 \/ one time\">$110 \/ one time<\/option><option value=\"$79 \/ hour\">$79 \/ hour<\/option><option value=\"$399 \/ day\">$399 \/ day<\/option><option value=\"$110 \/ one time\">$110 \/ one time<\/option><option value=\"$99 \/ hour\">$99 \/ hour<\/option><option value=\"$499 \/ day\">$499 \/ day<\/option><option value=\"$165 \/ one time\">$165 \/ one time<\/option><option value=\"$69 \/ hour\">$69 \/ hour<\/option><option value=\"$369 \/ day\">$369 \/ day<\/option><option value=\"$100 \/ one time\">$100 \/ one time<\/option><option value=\"$79 \/ hour\">$79 \/ hour<\/option><option value=\"$399 \/ day\">$399 \/ day<\/option><option value=\"$110 \/ one time\">$110 \/ one time<\/option><\/select><\/span>\n\t\t<\/p>\n\t<\/fieldset>\n\t<fieldset class=\"form-group col-md-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"location\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Pickup location\" value=\"\" type=\"text\" name=\"location\" \/><\/span>\n\t\t<\/p>\n\t<\/fieldset>\n<\/div>\n<div class=\"row\">\n\t<fieldset class=\"form-group col-md-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"date-picker\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-date\" aria-invalid=\"false\" placeholder=\"Select your date\" value=\"\" type=\"date\" name=\"date-picker\" \/><\/span>\n\t\t<\/p>\n\t<\/fieldset>\n\t<fieldset class=\"form-group col-md-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"destination\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Destination\" value=\"\" type=\"text\" name=\"destination\" \/><\/span>\n\t\t<\/p>\n\t<\/fieldset>\n<\/div>\n<div class=\"row\">\n\t<fieldset class=\"form-group col-md-12\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"note\"><textarea cols=\"40\" rows=\"3\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Additional note\" name=\"note\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/fieldset>\n\t<fieldset class=\"form-group col-md-12\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-normal btn-md\" type=\"submit\" value=\"Submit\" \/>\n\t\t<\/p>\n\t<\/fieldset>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2264","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-json\/wp\/v2\/pages\/2264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-json\/wp\/v2\/comments?post=2264"}],"version-history":[{"count":0,"href":"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-json\/wp\/v2\/pages\/2264\/revisions"}],"wp:attachment":[{"href":"https:\/\/preview.limorent.anpsthemes.com\/demo2\/wp-json\/wp\/v2\/media?parent=2264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}